{"id":1111,"date":"2016-01-28T10:09:40","date_gmt":"2016-01-28T10:09:40","guid":{"rendered":"http:\/\/gestaolegalnaadvocacia.com.br\/site\/?p=1111"},"modified":"2016-01-28T10:09:40","modified_gmt":"2016-01-28T10:09:40","slug":"conjur-oab-ira-ao-stf-contra-reducao-de-horario-em-tribunais","status":"publish","type":"post","link":"https:\/\/gestaolegalnaadvocacia.com.br\/site\/conjur-oab-ira-ao-stf-contra-reducao-de-horario-em-tribunais\/","title":{"rendered":"Conjur: OAB ir\u00e1 ao STF contra redu\u00e7\u00e3o de hor\u00e1rio em tribunais"},"content":{"rendered":"<p><a href=\"http:\/\/www.conjur.com.br\/2016-jan-27\/presidente-oab-ir-stf-horario-reduzido-cortes\">Bras\u00edlia &#8211; Confira reportagem da revista Consultor Jur\u00eddico, sobre as medidas anunciadas pelo presidente nacional da OAB, Marcus Vinicius Furtado Co\u00ealho, contra a redu\u00e7\u00e3o no hor\u00e1rio de atendimento ao p\u00fablico adotada por alguns tribunais:<\/a><\/p>\n<p>A redu\u00e7\u00e3o no hor\u00e1rio de atendimento ao p\u00fablico adotada por alguns tribunais para cortar gastos deve parar no Supremo Tribunal Federal. A promessa foi feita pelo presidente do Conselho Federal da Ordem dos Advogados do Brasil Marcus Vinicius Furtado Co\u00ealho, ao repudiar a medida.<\/p>\n<p>Muitos tribunais apenas alteraram o hor\u00e1rio de atendimento, iniciando e terminando seus trabalhos uma hora mais cedo. Mas alguns reduziram o atendimento. O Tribunal Regional do Trabalho da 14\u00aa Regi\u00e3o (RO-AC) antes atendia das 8h \u00e0s 18h e passou para 7h30 \u00e0s 14h30. No Tribunal Regional do Trabalho da 1\u00aa Regi\u00e3o (RJ), o funcionamento dos pr\u00e9dios ser\u00e1 reduzido em uma hora, das 8h \u00e0s 17h.<\/p>\n<p>Segundo Marcus Vinicius, a economia do Judici\u00e1rio deve ser feita de outras formas. \u201c\u00c9 descabido qualquer argumento para a redu\u00e7\u00e3o do expediente, quando a sociedade exige mais e melhores servi\u00e7os prestados pelo Judici\u00e1rio\u201d, disse o presidente da OAB.<\/p>\n<p>Leia abaixo a nota da entidade:<\/p>\n<p>Diante da redu\u00e7\u00e3o do hor\u00e1rio de expediente dos tribunais, anunciada em alguns estados do Brasil, o presidente do Conselho Federal da Ordem dos Advogados do Brasil, Marcus Vinicius Furtado Co\u00ealho, apresenta a sua firme repulsa e contrariedade \u00e0 medida.<\/p>\n<p>Em nome dos 945 mil advogados e da sociedade civil brasileira, o presidente da OAB considera descabido qualquer argumento para a redu\u00e7\u00e3o do expediente, quando a sociedade exige mais e melhores servi\u00e7os prestados pelo Judici\u00e1rio.<\/p>\n<p>A OAB adotar\u00e1 as medidas perante o Supremo Tribunal Federal no sentido de restabelecer o funcionamento pleno do Judici\u00e1rio, que deve funcionar os dois turnos. A economia de despesas do Judici\u00e1rio deve ser obtida de outras formas, jamais com o fechamento de suas portas ao acesso a justi\u00e7a.<\/p>\n<p>Fonte: <a href=\"http:\/\/www.oab.org.br\/noticia\/29237\/conjur-oab-ira-ao-stf-contra-reducao-de-horario-em-tribunais\">OAB Conselho Federal<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bras\u00edlia &#8211; Confira reportagem da revista Consultor Jur\u00eddico, sobre as medidas anunciadas pelo presidente nacional da OAB, Marcus Vinicius Furtado Co\u00ealho, contra a redu\u00e7\u00e3o no hor\u00e1rio<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":3,"featured_media":840,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1111","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categoria-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/gestaolegalnaadvocacia.com.br\/site\/wp-json\/wp\/v2\/posts\/1111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gestaolegalnaadvocacia.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gestaolegalnaadvocacia.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gestaolegalnaadvocacia.com.br\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/gestaolegalnaadvocacia.com.br\/site\/wp-json\/wp\/v2\/comments?post=1111"}],"version-history":[{"count":0,"href":"https:\/\/gestaolegalnaadvocacia.com.br\/site\/wp-json\/wp\/v2\/posts\/1111\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gestaolegalnaadvocacia.com.br\/site\/wp-json\/wp\/v2\/media\/840"}],"wp:attachment":[{"href":"https:\/\/gestaolegalnaadvocacia.com.br\/site\/wp-json\/wp\/v2\/media?parent=1111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gestaolegalnaadvocacia.com.br\/site\/wp-json\/wp\/v2\/categories?post=1111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gestaolegalnaadvocacia.com.br\/site\/wp-json\/wp\/v2\/tags?post=1111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}