{"id":1076,"date":"2016-01-12T13:57:03","date_gmt":"2016-01-12T13:57:03","guid":{"rendered":"http:\/\/gestaolegalnaadvocacia.com.br\/site\/?p=1076"},"modified":"2016-01-12T13:57:03","modified_gmt":"2016-01-12T13:57:03","slug":"mercado-piora-expectativa-para-inflacao-e-atividade-economica-em-2016","status":"publish","type":"post","link":"https:\/\/gestaolegalnaadvocacia.com.br\/site\/mercado-piora-expectativa-para-inflacao-e-atividade-economica-em-2016\/","title":{"rendered":"Mercado piora expectativa para infla\u00e7\u00e3o e atividade econ\u00f4mica em 2016"},"content":{"rendered":"<p class=\"sub-title\">Para 2017, o mercado segue prevendo infla\u00e7\u00e3o de 5,2%, menor que a deste ano<\/p>\n<p><b>Fonte:<\/b>\u00a0Valor Econ\u00f4mico<\/p>\n<p>As expectativas dos analistas de mercado a respeito da infla\u00e7\u00e3o e da atividade econ\u00f4mica iniciaram 2016 piores que no fim do ano anterior, de acordo com o relat\u00f3rio Focus, do Banco Central (BC).<\/p>\n<p>No boletim mais recente, a mediana das estimativas para o desempenho do Produto Interno Bruto (PIB) foi revisada pela 14\u00aa semana consecutiva e agora indica contra\u00e7\u00e3o de 2,99%, ante recuo de 2,95% previsto no documento anterior. Para 2017, a expectativa de crescimento da economia foi reduzida, de 1% para 0,86%.<\/p>\n<p>No caso da ind\u00fastria, a proje\u00e7\u00e3o \u00e9 de queda de 3,45% em 2016, um pouco menos intensa que a de 3,50% estimada antes. No ano que vem, a produ\u00e7\u00e3o deve crescer 1,98%, em vez dos 2% estimados antes.<\/p>\n<p>Quanto \u00e0 infla\u00e7\u00e3o, a mediana das estimativas para o \u00cdndice Nacional de Pre\u00e7os ao Consumidor Amplo (IPCA) subiu pela segunda semana seguida, de 6,87% para 6,93%. Na sexta-feira, o IBGE informou que, em 2015, o IPCA subiu 10,67%. Essa taxa de dois d\u00edgitos deixa uma \u201cheran\u00e7a\u201d pesada para este ano, o que tornar\u00e1 o combate ao aumento da infla\u00e7\u00e3o mais complicado. De acordo com especialistas ouvidos pelo Valor, por causa do alto n\u00edvel de indexa\u00e7\u00e3o da economia brasileira, a chamada in\u00e9rcia inflacion\u00e1ria pode responder a at\u00e9 20% da alta dos pre\u00e7os em 2016. As corre\u00e7\u00f5es do sal\u00e1rio m\u00ednimo e dos transportes p\u00fablicos s\u00e3o os primeiros sinais da infla\u00e7\u00e3o herdada de 2015.<\/p>\n<p>Para 2017, o mercado segue prevendo infla\u00e7\u00e3o de 5,2%, menor que a deste ano, mas ainda acima do centro da meta, de 4,5%. Em carta divulgada na sexta-feira para justificar o descumprimento da meta de infla\u00e7\u00e3o em 2015, o presidente do BC, Alexandre Tombini, reiterou que a autoridade monet\u00e1ria continuar\u00e1 a adotar as medidas necess\u00e1rias para que o IPCA convirja aos 4,5%.<\/p>\n<p>No Focus, os analistas n\u00e3o alteraram suas expectativas para a taxa Selic ao fim deste ano, de 15,25%, mas elevaram a estimativa para 2017, de 12,50% para 12,75%. A Selic est\u00e1, atualmente, em 14,25%.<\/p>\n<p>Entre os analistas Top 5, os que mais acertam as proje\u00e7\u00f5es, a mediana de suas estimativas de m\u00e9dio prazo para o IPCA de 2016 subiu de 7,44% para 7,49%. Para 2017, permaneceu em 5,50%. Quanto \u00e0 Selic, a aposta partiu de 13,75% para 15,25% neste ano e foi mantida a expectativa de que o juro caia at\u00e9 12,75% ao fim de 2017.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para 2017, o mercado segue prevendo infla\u00e7\u00e3o de 5,2%, menor que a deste ano Fonte:\u00a0Valor Econ\u00f4mico As expectativas dos analistas de mercado a respeito da infla\u00e7\u00e3o<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1076","post","type-post","status-publish","format-standard","hentry","category-categoria-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/gestaolegalnaadvocacia.com.br\/site\/wp-json\/wp\/v2\/posts\/1076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gestaolegalnaadvocacia.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gestaolegalnaadvocacia.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gestaolegalnaadvocacia.com.br\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/gestaolegalnaadvocacia.com.br\/site\/wp-json\/wp\/v2\/comments?post=1076"}],"version-history":[{"count":0,"href":"https:\/\/gestaolegalnaadvocacia.com.br\/site\/wp-json\/wp\/v2\/posts\/1076\/revisions"}],"wp:attachment":[{"href":"https:\/\/gestaolegalnaadvocacia.com.br\/site\/wp-json\/wp\/v2\/media?parent=1076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gestaolegalnaadvocacia.com.br\/site\/wp-json\/wp\/v2\/categories?post=1076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gestaolegalnaadvocacia.com.br\/site\/wp-json\/wp\/v2\/tags?post=1076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}